{"id":77682,"date":"2025-11-14T20:14:37","date_gmt":"2025-11-14T20:14:37","guid":{"rendered":"https:\/\/psychologydictionary.ae\/sous-depression-depression-mineure\/"},"modified":"2025-11-14T20:14:37","modified_gmt":"2025-11-14T20:14:37","slug":"sous-depression-depression-mineure","status":"publish","type":"post","link":"https:\/\/psychologydictionary.ae\/fr\/sous-depression-depression-mineure\/","title":{"rendered":"Sous-d\u00e9pression (d\u00e9pression mineure)"},"content":{"rendered":"<p>un \u00e9tat d\u00e9pressif qui n\u2019atteint pas le diagnostic de d\u00e9pression majeure en gravit\u00e9 et\/ou selon les crit\u00e8res diagnostiques formels de la CIM-10 \u2013 soit il n\u2019y a pas de sympt\u00f4mes n\u00e9cessaires au diagnostic de d\u00e9pression majeure, soit leur gravit\u00e9 est l\u00e9g\u00e8rement exprim\u00e9e, il n\u2019y a pas d\u2019alt\u00e9ration significative des fonctions vitales et du fonctionnement social. Crit\u00e8res diagnostiques : humeur d\u00e9pressive et anh\u00e9donie pendant au moins deux semaines, ainsi que deux des neuf crit\u00e8res pour la d\u00e9pression majeure. En d\u2019autres termes, une forme l\u00e9g\u00e8re de d\u00e9pression non psychotique, caract\u00e9ris\u00e9e par une humeur d\u00e9pressive persistante, une diminution de l\u2019activit\u00e9 et de l\u2019int\u00e9r\u00eat pour la vie quotidienne. Les sympt\u00f4mes de la sous-d\u00e9pression peuvent persister longtemps, parfois invisibles par une personne et son environnement.   <\/p>\n","protected":false},"excerpt":{"rendered":"<p>un \u00e9tat d\u00e9pressif qui n\u2019atteint pas le diagnostic de d\u00e9pression majeure en gravit\u00e9 et\/ou selon les crit\u00e8res diagnostiques formels de la CIM-10 \u2013 soit il n\u2019y a pas de sympt\u00f4mes n\u00e9cessaires au diagnostic de d\u00e9pression majeure, soit leur gravit\u00e9 est l\u00e9g\u00e8rement exprim\u00e9e, il n\u2019y a pas d\u2019alt\u00e9ration significative des fonctions vitales et du fonctionnement social. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[222],"tags":[],"class_list":["post-77682","post","type-post","status-publish","format-standard","hentry","category-definition-des-troubles-mentaux-et-techniques-de-traitement-appropriees"],"_links":{"self":[{"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/posts\/77682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/comments?post=77682"}],"version-history":[{"count":0,"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/posts\/77682\/revisions"}],"wp:attachment":[{"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/media?parent=77682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/categories?post=77682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/psychologydictionary.ae\/fr\/wp-json\/wp\/v2\/tags?post=77682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}